{"id":11902,"date":"2020-11-30T01:58:43","date_gmt":"2020-11-30T04:58:43","guid":{"rendered":"http:\/\/www.revistarescatados.com.ar\/web\/?p=11902"},"modified":"2020-11-30T01:58:45","modified_gmt":"2020-11-30T04:58:45","slug":"desinfectan-cajeros-en-calchaqui","status":"publish","type":"post","link":"https:\/\/www.revistarescatados.com.ar\/web\/2020\/11\/30\/desinfectan-cajeros-en-calchaqui\/","title":{"rendered":"Desinfectan cajeros en Calchaqu\u00ed"},"content":{"rendered":"\n<p> <br><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"732\" src=\"http:\/\/www.revistarescatados.com.ar\/web\/wp-content\/uploads\/2020\/11\/cajeros-desinfeccion-1024x732.jpg\" alt=\"\" class=\"wp-image-11903\" srcset=\"https:\/\/www.revistarescatados.com.ar\/web\/wp-content\/uploads\/2020\/11\/cajeros-desinfeccion-1024x732.jpg 1024w, https:\/\/www.revistarescatados.com.ar\/web\/wp-content\/uploads\/2020\/11\/cajeros-desinfeccion-300x214.jpg 300w, https:\/\/www.revistarescatados.com.ar\/web\/wp-content\/uploads\/2020\/11\/cajeros-desinfeccion-768x549.jpg 768w, https:\/\/www.revistarescatados.com.ar\/web\/wp-content\/uploads\/2020\/11\/cajeros-desinfeccion.jpg 1108w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><strong><span class=\"has-inline-color has-vivid-red-color\">Contin\u00faan las tareas de desinfecci\u00f3n en los sectores de los cajeros autom\u00e1ticos de los Bancos, en los accesos de las Mutuales y de los supermercados. <\/span><\/strong><\/p>\n\n\n\n<p><br>Estas acciones preventivas se vienen llevando adelante en conjunto entre el \u00c1rea de Control de Vectores Municipal y el sector de Chagas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Contin\u00faan las tareas de desinfecci\u00f3n en los sectores de los cajeros autom\u00e1ticos de los Bancos, en los accesos de las Mutuales y de los supermercados. Estas acciones preventivas se vienen llevando adelante&#46;&#46;&#46;<\/p>\n","protected":false},"author":1,"featured_media":11903,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2,3,16,8],"tags":[],"_links":{"self":[{"href":"https:\/\/www.revistarescatados.com.ar\/web\/wp-json\/wp\/v2\/posts\/11902"}],"collection":[{"href":"https:\/\/www.revistarescatados.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.revistarescatados.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.revistarescatados.com.ar\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.revistarescatados.com.ar\/web\/wp-json\/wp\/v2\/comments?post=11902"}],"version-history":[{"count":1,"href":"https:\/\/www.revistarescatados.com.ar\/web\/wp-json\/wp\/v2\/posts\/11902\/revisions"}],"predecessor-version":[{"id":11904,"href":"https:\/\/www.revistarescatados.com.ar\/web\/wp-json\/wp\/v2\/posts\/11902\/revisions\/11904"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.revistarescatados.com.ar\/web\/wp-json\/wp\/v2\/media\/11903"}],"wp:attachment":[{"href":"https:\/\/www.revistarescatados.com.ar\/web\/wp-json\/wp\/v2\/media?parent=11902"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.revistarescatados.com.ar\/web\/wp-json\/wp\/v2\/categories?post=11902"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.revistarescatados.com.ar\/web\/wp-json\/wp\/v2\/tags?post=11902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}