{"id":25956,"date":"2026-05-12T22:35:27","date_gmt":"2026-05-13T01:35:27","guid":{"rendered":"https:\/\/www.revistarescatados.com.ar\/web\/?p=25956"},"modified":"2026-05-12T22:35:27","modified_gmt":"2026-05-13T01:35:27","slug":"detienen-a-una-pareja-por-hurtar-camisetas-y-bufandas-de-la-seleccion-argentina-en-un-comercio-de-reconquista","status":"publish","type":"post","link":"https:\/\/www.revistarescatados.com.ar\/web\/2026\/05\/12\/detienen-a-una-pareja-por-hurtar-camisetas-y-bufandas-de-la-seleccion-argentina-en-un-comercio-de-reconquista\/","title":{"rendered":"Detienen a una pareja por hurtar camisetas y bufandas de la selecci\u00f3n argentina en un comercio de Reconquista"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><strong>La Polic\u00eda de Investigaciones, dependiente del Ministerio de Justicia y Seguridad de la provincia de Santa Fe &#8211; Regi\u00f3n IV, detuvo en las \u00faltimas horas a una pareja, en el marco de una investigaci\u00f3n por una serie de hurtos reiterados cometidos en un local comercial de la ciudad de Reconquista.<\/strong><\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-large wp-image-25957\" src=\"http:\/\/www.revistarescatados.com.ar\/web\/wp-content\/uploads\/2026\/05\/PDI-1024x768.jpg\" alt=\"\" width=\"1024\" height=\"768\" srcset=\"https:\/\/www.revistarescatados.com.ar\/web\/wp-content\/uploads\/2026\/05\/PDI-1024x768.jpg 1024w, https:\/\/www.revistarescatados.com.ar\/web\/wp-content\/uploads\/2026\/05\/PDI-300x225.jpg 300w, https:\/\/www.revistarescatados.com.ar\/web\/wp-content\/uploads\/2026\/05\/PDI-768x576.jpg 768w, https:\/\/www.revistarescatados.com.ar\/web\/wp-content\/uploads\/2026\/05\/PDI.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>Seg\u00fan la denuncia, una mujer y un hombre ingresaron en distintas ocasiones a un comercio y sustrajeron perfumes, camisetas y bufandas de la Selecci\u00f3n Argentina, hechos que quedaron registrados por las c\u00e1maras de seguridad del lugar. El \u00faltimo episodio ocurri\u00f3 el 9 de mayo, cuando la propietaria del negocio reconoci\u00f3 a los sospechosos e intent\u00f3 revisar el bolso de la mujer, produci\u00e9ndose un forcejeo en el que result\u00f3 lesionada.<\/p>\n<p>Tras tareas investigativas, la PDI identific\u00f3 a los involucrados como M. D. G. de 29 a\u00f1os, y E. M. M. de 28, quienes fueron detenidos una vivienda ubicada en inmediaciones de la Ruta 40 S \u2013 Piezas de Caritas, tras una orden de allanamiento otorgada por la Dra. Bressan. Adem\u00e1s en el procedimiento secuestraron prendas de vestir, un mechero rojo y una cartera con maquillaje.<\/p>\n<p>Por disposici\u00f3n fiscal el hombre fue trasladado a sede policial, en tanto la mujer cumplir\u00e1 la medida en su domicilio bajo el art\u00edculo 10 del C\u00f3digo Penal, a disposici\u00f3n de la justicia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; La Polic\u00eda de Investigaciones, dependiente del Ministerio de Justicia y Seguridad de la provincia de Santa Fe &#8211; Regi\u00f3n IV, detuvo en las \u00faltimas horas a una pareja, en el marco&#46;&#46;&#46;<\/p>\n","protected":false},"author":1,"featured_media":25957,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[6,16,11,8],"tags":[],"_links":{"self":[{"href":"https:\/\/www.revistarescatados.com.ar\/web\/wp-json\/wp\/v2\/posts\/25956"}],"collection":[{"href":"https:\/\/www.revistarescatados.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.revistarescatados.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.revistarescatados.com.ar\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.revistarescatados.com.ar\/web\/wp-json\/wp\/v2\/comments?post=25956"}],"version-history":[{"count":1,"href":"https:\/\/www.revistarescatados.com.ar\/web\/wp-json\/wp\/v2\/posts\/25956\/revisions"}],"predecessor-version":[{"id":25958,"href":"https:\/\/www.revistarescatados.com.ar\/web\/wp-json\/wp\/v2\/posts\/25956\/revisions\/25958"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.revistarescatados.com.ar\/web\/wp-json\/wp\/v2\/media\/25957"}],"wp:attachment":[{"href":"https:\/\/www.revistarescatados.com.ar\/web\/wp-json\/wp\/v2\/media?parent=25956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.revistarescatados.com.ar\/web\/wp-json\/wp\/v2\/categories?post=25956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.revistarescatados.com.ar\/web\/wp-json\/wp\/v2\/tags?post=25956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}