{"id":26147,"date":"2026-07-14T01:16:23","date_gmt":"2026-07-14T04:16:23","guid":{"rendered":"https:\/\/www.revistarescatados.com.ar\/web\/?p=26147"},"modified":"2026-07-14T01:16:23","modified_gmt":"2026-07-14T04:16:23","slug":"el-calvario-de-una-mujer-acosada-en-calchaqui","status":"publish","type":"post","link":"https:\/\/www.revistarescatados.com.ar\/web\/2026\/07\/14\/el-calvario-de-una-mujer-acosada-en-calchaqui\/","title":{"rendered":"El calvario de una mujer acosada en Calchaqu\u00ed"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><strong>Desde hace dos a\u00f1os, una joven madre y estudiante es acosada por un hombre de 43 a\u00f1os, que fue aprehendido hace unos d\u00edas por violar tres veces la orden judicial de restricci\u00f3n perimetral. Su crudo testimonio y una justicia ausente.<\/strong><\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-large wp-image-26148\" src=\"http:\/\/www.revistarescatados.com.ar\/web\/wp-content\/uploads\/2026\/07\/acosador-1024x733.jpg\" alt=\"\" width=\"1024\" height=\"733\" srcset=\"https:\/\/www.revistarescatados.com.ar\/web\/wp-content\/uploads\/2026\/07\/acosador-1024x733.jpg 1024w, https:\/\/www.revistarescatados.com.ar\/web\/wp-content\/uploads\/2026\/07\/acosador-300x215.jpg 300w, https:\/\/www.revistarescatados.com.ar\/web\/wp-content\/uploads\/2026\/07\/acosador-768x550.jpg 768w, https:\/\/www.revistarescatados.com.ar\/web\/wp-content\/uploads\/2026\/07\/acosador.jpg 1191w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>L.T.T. tiene 30 a\u00f1os de edad, vive en la ciudad de Calchaqu\u00ed con miedo y siempre sale acompa\u00f1ada. Es estudiante en la EEMPA 1050 y emprendedora. Desde abril del 2024 es acosada por Jos\u00e9 Mar\u00eda S. de 43 a\u00f1os de edad.<\/p>\n<p>Su mam\u00e1 falleci\u00f3 el 8 de marzo de ese a\u00f1o y al mes siguiente inici\u00f3 este calvario . \u201c<em><strong>Este se\u00f1or me ha acosado desde entonces y no he tenido una vida normal, deje de hacer muchas cosas por miedo<\/strong><\/em>. Me segu\u00eda a todos lados, e incluso ha dejado\u00a0 objetos fuera de casa que tir\u00e9 a la basura. Pasaba por mi casa todos los d\u00edas, durante estos dos a\u00f1os, con cuchillos haciendo se\u00f1as y dem\u00e1s. Saliendo de la escuela &#8211; llegando a la virgen sobre Ituzaing\u00f3 &#8211; me sigui\u00f3 con un cuchillo y en la desesperaci\u00f3n corr\u00ed como pude hasta llegar a casa. Mi pap\u00e1 llam\u00f3 a la polic\u00eda pero no lo encontraron\u201d, relat\u00f3.<\/p>\n<p>Tambi\u00e9n expuso que no le tomaban las denuncias porque \u201c<em><strong>el tipo no era ni pareja ni ex pareja ni ten\u00edamos un v\u00ednculo familiar. Si la polic\u00eda no me pod\u00eda ayudar nadie lo iba a poder hacer&#8230;as\u00ed que todo sigui\u00f3 igual o peor\u201d<\/strong><\/em>, cont\u00f3<\/p>\n<p>Este a\u00f1o volvi\u00f3 a la escuela nocturna pero el acoso continu\u00f3, incluso cuando por la ma\u00f1ana llevaba su peque\u00f1a hija a una instituci\u00f3n educativa de nivel primario. Le dejaba flores en su bicicleta, y se sentaba en la plaza. \u201c<strong><em>Le cuento la situaci\u00f3n a mi profesora &#8211; gracias a ella pude hacer las denuncias &#8211; y me dieron esta medida de distancia el 2 de junio de este a\u00f1o. Desde entonces ya la desobedeci\u00f3 tres veces, esper\u00e1ndome en el Parque Prensa, cerca de la escuela o en la esquina de casa<\/em><\/strong>\u201d, indic\u00f3.<\/p>\n<p>\u201cNo puedo tener una vida normal, ni sentarme afuera de casa porque este se\u00f1or me vive acosando, no puedo llevar a mi hija a la escuela, no salgo si no es acompa\u00f1ada de mi pap\u00e1 o de mis hermanos. No es vida la que estoy viviendo y no es justo tener que detener mi vida por esta situaci\u00f3n angustiante. <em><strong>Salgo rezando de casa para no cruzarme con esta persona y para poder llegar a la escuela sana y salva<\/strong><\/em>. Me voy de casa despidi\u00e9ndome\u00a0 de mi hija, mi pap\u00e1 y mis hermanos dici\u00e9ndoles que los Amo por si un d\u00eda de estos ya no puedo volver, porque no s\u00e9 lo que pasa por la cabeza de este se\u00f1or que se obsesion\u00f3 conmigo y ya no s\u00e9 qu\u00e9 pensar\u201d, narr\u00f3.<\/p>\n<p>Tambi\u00e9n adelant\u00f3 que recurrir\u00e1 a la fiscal\u00eda en turno para plantear su cruda realidad y reclamar su derecho a vivir segura.<\/p>\n<p><strong>PARTE POLICIAL<\/strong><\/p>\n<p>En el marco de una causa por desobediencia a un mandato judicial, personal del \u00c1rea de Investigaci\u00f3n sobre Violencia de G\u00e9nero, Familiar y Sexual de Calchaqu\u00ed, dependiente de la Agencia de Investigaciones sobre Trata de Personas y Violencia de G\u00e9nero \u2013 Regi\u00f3n IV de la Polic\u00eda de Investigaciones (PDI), detuvo a un hombre.<\/p>\n<p>La actuaci\u00f3n se origin\u00f3 a partir de la intervenci\u00f3n de personal del Comando Radioel\u00e9ctrico de la Unidad Regional XIX, quienes procedieron a la aprehensi\u00f3n de un hombre por incumplir una medida judicial de restricci\u00f3n de acercamiento vigente.<\/p>\n<p>Por disposici\u00f3n del fiscal Valent\u00edn Here\u00f1\u00fa, del Ministerio P\u00fablico de la Acusaci\u00f3n de Vera, se procedi\u00f3 a la detenci\u00f3n de J.M.S., de 43 a\u00f1os. El detenido qued\u00f3 alojado en la Secci\u00f3n Alcaid\u00eda de la Unidad Regional XIX, a disposici\u00f3n de la Fiscal\u00eda interviniente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Desde hace dos a\u00f1os, una joven madre y estudiante es acosada por un hombre de 43 a\u00f1os, que fue aprehendido hace unos d\u00edas por violar tres veces la orden judicial de&#46;&#46;&#46;<\/p>\n","protected":false},"author":1,"featured_media":26148,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2,3,16,8],"tags":[],"_links":{"self":[{"href":"https:\/\/www.revistarescatados.com.ar\/web\/wp-json\/wp\/v2\/posts\/26147"}],"collection":[{"href":"https:\/\/www.revistarescatados.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.revistarescatados.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.revistarescatados.com.ar\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.revistarescatados.com.ar\/web\/wp-json\/wp\/v2\/comments?post=26147"}],"version-history":[{"count":1,"href":"https:\/\/www.revistarescatados.com.ar\/web\/wp-json\/wp\/v2\/posts\/26147\/revisions"}],"predecessor-version":[{"id":26149,"href":"https:\/\/www.revistarescatados.com.ar\/web\/wp-json\/wp\/v2\/posts\/26147\/revisions\/26149"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.revistarescatados.com.ar\/web\/wp-json\/wp\/v2\/media\/26148"}],"wp:attachment":[{"href":"https:\/\/www.revistarescatados.com.ar\/web\/wp-json\/wp\/v2\/media?parent=26147"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.revistarescatados.com.ar\/web\/wp-json\/wp\/v2\/categories?post=26147"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.revistarescatados.com.ar\/web\/wp-json\/wp\/v2\/tags?post=26147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}